{"id":3109,"date":"2013-01-28T23:36:43","date_gmt":"2013-01-28T22:36:43","guid":{"rendered":"http:\/\/editorialmediterraneatest.grupoormo.com\/?post_type=product&#038;p=3109"},"modified":"2019-03-20T19:18:55","modified_gmt":"2019-03-20T18:18:55","slug":"petita-historia-del-bisbe-masnou","status":"publish","type":"product","link":"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/","title":{"rendered":"Petita Hist\u00f2ria del bisbe Masnou"},"content":{"rendered":"<p style=\"text-align: justify;\">Aquesta petita hist\u00f2ria explica als nens i nenes la vida del bisbe Masnou, un fill de pastors que va arribar a ser bisbe de Vic l\u2019any 1952 i que va defensar la legitimitat del nacionalisme catal\u00e0 en moltes de les seves obres. El text va acompanyat de les il\u00b7lustracions a tot color de Pilar\u00edn Bay\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aquesta petita hist\u00f2ria explica als nens i nenes la vida del bisbe Masnou, un fill de pastors que va arribar a ser bisbe de Vic l\u2019any 1952 i que va defensar la legitimitat del nacionalisme catal\u00e0 en moltes de les seves obres. El text va acompanyat de les il\u00b7lustracions a tot color de Pilar\u00edn Bay\u00e9s.<\/p>\n","protected":false},"featured_media":24529,"template":"","meta":[],"product_cat":[16,73],"product_tag":[377,4362],"autors":[],"class_list":{"0":"post-3109","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-editorial-mediterrania","7":"product_cat-petites-histories","8":"product_tag-llibre-infantil","9":"product_tag-pilarin-bayes","11":"first","12":"outofstock","13":"purchasable","14":"product-type-simple","swatches":"rey-swatches","show_selected":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Petita Hist\u00f2ria del bisbe Masnou - Editorial Mediterrania<\/title>\n<meta name=\"description\" content=\"Llibre infantil educatiu petita hist\u00f2ria sobre la vida del bisbe Masnou per a nens i nenes entre 8 i 12 anys\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petita Hist\u00f2ria del bisbe Masnou - Editorial Mediterrania\" \/>\n<meta property=\"og:description\" content=\"Llibre infantil educatiu petita hist\u00f2ria sobre la vida del bisbe Masnou per a nens i nenes entre 8 i 12 anys\" \/>\n<meta property=\"og:url\" content=\"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/\" \/>\n<meta property=\"og:site_name\" content=\"Editorial Mediterr\u00e0nia\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-20T18:18:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/editorialmediterrania.com\/wp-content\/uploads\/2013\/01\/Petita-Historia-del-bisbe-Masnou.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"727\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@edmediterrania\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/\",\"url\":\"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/\",\"name\":\"Petita Hist\u00f2ria del bisbe Masnou - Editorial Mediterrania\",\"isPartOf\":{\"@id\":\"https:\/\/editorialmediterrania.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/editorialmediterrania.com\/wp-content\/uploads\/2013\/01\/Petita-Historia-del-bisbe-Masnou.jpg\",\"datePublished\":\"2013-01-28T22:36:43+00:00\",\"dateModified\":\"2019-03-20T18:18:55+00:00\",\"description\":\"Llibre infantil educatiu petita hist\u00f2ria sobre la vida del bisbe Masnou per a nens i nenes entre 8 i 12 anys\",\"breadcrumb\":{\"@id\":\"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/#primaryimage\",\"url\":\"https:\/\/editorialmediterrania.com\/wp-content\/uploads\/2013\/01\/Petita-Historia-del-bisbe-Masnou.jpg\",\"contentUrl\":\"https:\/\/editorialmediterrania.com\/wp-content\/uploads\/2013\/01\/Petita-Historia-del-bisbe-Masnou.jpg\",\"width\":600,\"height\":727},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Children&#8217;s art book store\",\"item\":\"https:\/\/editorialmediterrania.com\/en\/childrens-art-book-store\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Petita Hist\u00f2ria del bisbe Masnou\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/editorialmediterrania.com\/en\/#website\",\"url\":\"https:\/\/editorialmediterrania.com\/en\/\",\"name\":\"Editorial Mediterrania\",\"description\":\"Llibres que t\u2019obriran nous mons\",\"publisher\":{\"@id\":\"https:\/\/editorialmediterrania.com\/en\/#organization\"},\"alternateName\":\"Llibres infantils d'art, cultura i natura\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/editorialmediterrania.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/editorialmediterrania.com\/en\/#organization\",\"name\":\"Editorial Mediterrania\",\"alternateName\":\"Llibres d'art, cultura i natura per infants i fam\u00edlies\",\"url\":\"https:\/\/editorialmediterrania.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/editorialmediterrania.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/editorialmediterrania.com\/wp-content\/uploads\/2023\/03\/LOGO-ED_MEDITERRANIA_OK-2.png\",\"contentUrl\":\"https:\/\/editorialmediterrania.com\/wp-content\/uploads\/2023\/03\/LOGO-ED_MEDITERRANIA_OK-2.png\",\"width\":1200,\"height\":300,\"caption\":\"Editorial Mediterrania\"},\"image\":{\"@id\":\"https:\/\/editorialmediterrania.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/edmediterrania\",\"https:\/\/www.instagram.com\/editorialmediterrania\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Petita Hist\u00f2ria del bisbe Masnou - Editorial Mediterrania","description":"Llibre infantil educatiu petita hist\u00f2ria sobre la vida del bisbe Masnou per a nens i nenes entre 8 i 12 anys","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/","og_locale":"en_US","og_type":"article","og_title":"Petita Hist\u00f2ria del bisbe Masnou - Editorial Mediterrania","og_description":"Llibre infantil educatiu petita hist\u00f2ria sobre la vida del bisbe Masnou per a nens i nenes entre 8 i 12 anys","og_url":"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/","og_site_name":"Editorial Mediterr\u00e0nia","article_modified_time":"2019-03-20T18:18:55+00:00","og_image":[{"width":600,"height":727,"url":"https:\/\/editorialmediterrania.com\/wp-content\/uploads\/2013\/01\/Petita-Historia-del-bisbe-Masnou.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@edmediterrania","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/","url":"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/","name":"Petita Hist\u00f2ria del bisbe Masnou - Editorial Mediterrania","isPartOf":{"@id":"https:\/\/editorialmediterrania.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/#primaryimage"},"image":{"@id":"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/#primaryimage"},"thumbnailUrl":"https:\/\/editorialmediterrania.com\/wp-content\/uploads\/2013\/01\/Petita-Historia-del-bisbe-Masnou.jpg","datePublished":"2013-01-28T22:36:43+00:00","dateModified":"2019-03-20T18:18:55+00:00","description":"Llibre infantil educatiu petita hist\u00f2ria sobre la vida del bisbe Masnou per a nens i nenes entre 8 i 12 anys","breadcrumb":{"@id":"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/#primaryimage","url":"https:\/\/editorialmediterrania.com\/wp-content\/uploads\/2013\/01\/Petita-Historia-del-bisbe-Masnou.jpg","contentUrl":"https:\/\/editorialmediterrania.com\/wp-content\/uploads\/2013\/01\/Petita-Historia-del-bisbe-Masnou.jpg","width":600,"height":727},{"@type":"BreadcrumbList","@id":"https:\/\/editorialmediterrania.com\/en\/product\/petita-historia-del-bisbe-masnou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Children&#8217;s art book store","item":"https:\/\/editorialmediterrania.com\/en\/childrens-art-book-store\/"},{"@type":"ListItem","position":2,"name":"Petita Hist\u00f2ria del bisbe Masnou"}]},{"@type":"WebSite","@id":"https:\/\/editorialmediterrania.com\/en\/#website","url":"https:\/\/editorialmediterrania.com\/en\/","name":"Editorial Mediterrania","description":"Llibres que t\u2019obriran nous mons","publisher":{"@id":"https:\/\/editorialmediterrania.com\/en\/#organization"},"alternateName":"Llibres infantils d'art, cultura i natura","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/editorialmediterrania.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/editorialmediterrania.com\/en\/#organization","name":"Editorial Mediterrania","alternateName":"Llibres d'art, cultura i natura per infants i fam\u00edlies","url":"https:\/\/editorialmediterrania.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/editorialmediterrania.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/editorialmediterrania.com\/wp-content\/uploads\/2023\/03\/LOGO-ED_MEDITERRANIA_OK-2.png","contentUrl":"https:\/\/editorialmediterrania.com\/wp-content\/uploads\/2023\/03\/LOGO-ED_MEDITERRANIA_OK-2.png","width":1200,"height":300,"caption":"Editorial Mediterrania"},"image":{"@id":"https:\/\/editorialmediterrania.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/edmediterrania","https:\/\/www.instagram.com\/editorialmediterrania\/"]}]}},"_links":{"self":[{"href":"https:\/\/editorialmediterrania.com\/en\/wp-json\/wp\/v2\/product\/3109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/editorialmediterrania.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/editorialmediterrania.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/editorialmediterrania.com\/en\/wp-json\/wp\/v2\/media\/24529"}],"wp:attachment":[{"href":"https:\/\/editorialmediterrania.com\/en\/wp-json\/wp\/v2\/media?parent=3109"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/editorialmediterrania.com\/en\/wp-json\/wp\/v2\/product_cat?post=3109"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/editorialmediterrania.com\/en\/wp-json\/wp\/v2\/product_tag?post=3109"},{"taxonomy":"autors","embeddable":true,"href":"https:\/\/editorialmediterrania.com\/en\/wp-json\/wp\/v2\/autors?post=3109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}